{"id":3092,"date":"2025-07-29T16:12:10","date_gmt":"2025-07-29T19:12:10","guid":{"rendered":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/?post_type=professor&#038;p=3092"},"modified":"2025-07-29T16:13:24","modified_gmt":"2025-07-29T19:13:24","slug":"cinzia-di-paolantonio","status":"publish","type":"professor","link":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/professor\/cinzia-di-paolantonio\/","title":{"rendered":"Cinzia Di Paolantonio"},"content":{"rendered":"<p style=\"text-align: left;\">Mi chiamo Cinzia Di Paolantonio e vivo a Genova in Italia.<br \/>\nMi piace guidare le persone a connettersi con il proprio corpo, non solo per ritrovare energia,\u00a0flessibilit\u00e0 e tonicit\u00e0, ma per sperimentare uno straordinario canale di trasformazione\u00a0profonda, capace di risvegliare l&#8217;attenzione allo stupore della vita e di portare grazia nel\u00a0vissuto quotidiano.<br \/>\nIl movimento per me non \u00e8 solo disciplina fisica, ma \u00e8 qualcosa di pi\u00f9 ampio e ricco di\u00a0sfumature introspettive, emotive, artistiche, espressive e spirituali.<br \/>\nIl mio primo e pi\u00f9 grande amore? La danza, che pratico fin da quando ero bambina.\u00a0Giovanissima ho iniziato a lavorare nel mondo del fitness, aggiungendo di anno in anno\u00a0sempre nuove discipline alla mia formazione, come il pilates matwork e l&#8217;allenamento\u00a0funzionale.<br \/>\nDurante la scuola superiore, grazie ad una prof di educazione fisica ho incontrato per la\u00a0prima volta lo yoga che ho iniziato a praticare. Nel 2017 decido di certificarmi 200 RYT e di\u00a0dedicarmi anche all&#8217;insegnamento dell&#8217;hatha yoga. Successivamente mi sono specializzata\u00a0nello yoga Pre e post parto e in yoga ormonale per la salute della donna certificandomi direttamente con la creatrice del metodo Dinah Rodrigues.<br \/>\nSono laureata in scienze della formazione e ho studiato al Teatro dell&#8217;Ortica qualificandomi\u00a0come operatore pedagogico teatrale.<br \/>\nContemporaneamente mi sto formando in danzamovimentoterapia espressiva\u00a0psicodinamica.<\/p>\n<p style=\"text-align: left;\"><a href=\"https:\/\/www.facebook.com\/cinziacla\">https:\/\/www.facebook.com\/cinziacla<\/a><\/p>\n<p style=\"text-align: left;\"><a href=\"https:\/\/www.instagram.com\/cinzia.alchimia.del.movimento\">https:\/\/www.instagram.com\/cinzia.alchimia.del.movimento<\/a><\/p>\n<p>&nbsp;<\/p>\n<div dir=\"auto\">\n<div dir=\"auto\">Corso online : ciclo di 5 incontri per imparare o ripassare la sequenza il mercoled\u00ec ore 18-19,15 dal 10 gennaio<\/div>\n<div dir=\"auto\">Corso settimanale in presenza a Genova il venerd\u00ec ore 18-19,15<\/div>\n<div dir=\"auto\">Workshop a Genova sabato 24 febbraio ore 9,30 &#8211; 13,30<\/div>\n<\/div>\n","protected":false},"featured_media":3093,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"cybocfi_hide_featured_image":""},"local":[225],"class_list":["post-3092","professor","type-professor","status-publish","has-post-thumbnail","hentry","local-italy"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cinzia Di Paolantonio - NYTH<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/professor\/cinzia-di-paolantonio\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cinzia Di Paolantonio - NYTH\" \/>\n<meta property=\"og:description\" content=\"Mi chiamo Cinzia Di Paolantonio e vivo a Genova in Italia. Mi piace guidare le persone a connettersi con il proprio corpo, non solo per ritrovare energia,\u00a0flessibilit\u00e0 e tonicit\u00e0, ma per sperimentare uno straordinario canale di trasformazione\u00a0profonda, capace di risvegliare l&#8217;attenzione allo stupore della vita e di portare grazia nel\u00a0vissuto quotidiano. Il movimento per me [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/professor\/cinzia-di-paolantonio\/\" \/>\n<meta property=\"og:site_name\" content=\"NYTH\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-29T19:13:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/wp-content\/uploads\/2025\/07\/Cinzia-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/classroom\\\/professor\\\/cinzia-di-paolantonio\\\/\",\"url\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/classroom\\\/professor\\\/cinzia-di-paolantonio\\\/\",\"name\":\"Cinzia Di Paolantonio - NYTH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/classroom\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/classroom\\\/professor\\\/cinzia-di-paolantonio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/classroom\\\/professor\\\/cinzia-di-paolantonio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/classroom\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Cinzia-2.jpg\",\"datePublished\":\"2025-07-29T19:12:10+00:00\",\"dateModified\":\"2025-07-29T19:13:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/classroom\\\/professor\\\/cinzia-di-paolantonio\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/classroom\\\/professor\\\/cinzia-di-paolantonio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/classroom\\\/professor\\\/cinzia-di-paolantonio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/classroom\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Cinzia-2.jpg\",\"contentUrl\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/classroom\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Cinzia-2.jpg\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/classroom\\\/professor\\\/cinzia-di-paolantonio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/classroom\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Professores\",\"item\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/classroom\\\/professor\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cinzia Di Paolantonio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/classroom\\\/#website\",\"url\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/classroom\\\/\",\"name\":\"NYTH\",\"description\":\"N\u00facleo de Yoga Terapia Hormonal\",\"publisher\":{\"@id\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/classroom\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/classroom\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/classroom\\\/#organization\",\"name\":\"Nucleo Yoga Terapia Hormonal - NYTH\",\"url\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/classroom\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/classroom\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/classroom\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/classroom\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/favicon.png\",\"width\":500,\"height\":500,\"caption\":\"Nucleo Yoga Terapia Hormonal - NYTH\"},\"image\":{\"@id\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/classroom\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cinzia Di Paolantonio - NYTH","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/professor\/cinzia-di-paolantonio\/","og_locale":"pt_BR","og_type":"article","og_title":"Cinzia Di Paolantonio - NYTH","og_description":"Mi chiamo Cinzia Di Paolantonio e vivo a Genova in Italia. Mi piace guidare le persone a connettersi con il proprio corpo, non solo per ritrovare energia,\u00a0flessibilit\u00e0 e tonicit\u00e0, ma per sperimentare uno straordinario canale di trasformazione\u00a0profonda, capace di risvegliare l&#8217;attenzione allo stupore della vita e di portare grazia nel\u00a0vissuto quotidiano. Il movimento per me [&hellip;]","og_url":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/professor\/cinzia-di-paolantonio\/","og_site_name":"NYTH","article_modified_time":"2025-07-29T19:13:24+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/wp-content\/uploads\/2025\/07\/Cinzia-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/professor\/cinzia-di-paolantonio\/","url":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/professor\/cinzia-di-paolantonio\/","name":"Cinzia Di Paolantonio - NYTH","isPartOf":{"@id":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/professor\/cinzia-di-paolantonio\/#primaryimage"},"image":{"@id":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/professor\/cinzia-di-paolantonio\/#primaryimage"},"thumbnailUrl":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/wp-content\/uploads\/2025\/07\/Cinzia-2.jpg","datePublished":"2025-07-29T19:12:10+00:00","dateModified":"2025-07-29T19:13:24+00:00","breadcrumb":{"@id":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/professor\/cinzia-di-paolantonio\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/professor\/cinzia-di-paolantonio\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/professor\/cinzia-di-paolantonio\/#primaryimage","url":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/wp-content\/uploads\/2025\/07\/Cinzia-2.jpg","contentUrl":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/wp-content\/uploads\/2025\/07\/Cinzia-2.jpg","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/professor\/cinzia-di-paolantonio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/"},{"@type":"ListItem","position":2,"name":"Professores","item":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/professor\/"},{"@type":"ListItem","position":3,"name":"Cinzia Di Paolantonio"}]},{"@type":"WebSite","@id":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/#website","url":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/","name":"NYTH","description":"N\u00facleo de Yoga Terapia Hormonal","publisher":{"@id":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/#organization","name":"Nucleo Yoga Terapia Hormonal - NYTH","url":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/#\/schema\/logo\/image\/","url":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/wp-content\/uploads\/2022\/05\/favicon.png","contentUrl":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/wp-content\/uploads\/2022\/05\/favicon.png","width":500,"height":500,"caption":"Nucleo Yoga Terapia Hormonal - NYTH"},"image":{"@id":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/wp-json\/wp\/v2\/professor\/3092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/wp-json\/wp\/v2\/professor"}],"about":[{"href":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/wp-json\/wp\/v2\/types\/professor"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/wp-json\/wp\/v2\/media\/3093"}],"wp:attachment":[{"href":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/wp-json\/wp\/v2\/media?parent=3092"}],"wp:term":[{"taxonomy":"local","embeddable":true,"href":"https:\/\/nucleoyogaterapiahormonal.com.br\/classroom\/wp-json\/wp\/v2\/local?post=3092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}