{"id":3126,"date":"2025-07-29T16:44:35","date_gmt":"2025-07-29T19:44:35","guid":{"rendered":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/?post_type=professor&#038;p=3126"},"modified":"2025-07-29T16:44:35","modified_gmt":"2025-07-29T19:44:35","slug":"miss-mary","status":"publish","type":"professor","link":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/professor\/miss-mary\/","title":{"rendered":"Miss Mary"},"content":{"rendered":"<div dir=\"auto\">\n<div id=\":ta\" class=\"Am aO9 Al editable LW-avf tS-tW tS-tY\" tabindex=\"1\" role=\"textbox\" contenteditable=\"true\" spellcheck=\"false\" aria-label=\"Corpo da mensagem\" aria-multiline=\"true\" aria-owns=\":w6\" aria-controls=\":w6\">\n<div dir=\"auto\">\n<div dir=\"auto\">Fin da bambina mi chiamano Miss\u00a0<span class=\"il\">Mary<\/span>.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Quando Dinah nel 2019 mi ha consegnato il diploma ed il libro, ha scritto una dedica: \u201cRemember Yama &amp; Niyama\u201d\u00a0Praticare lo Yoga Ormonale con il metodo di Dinah Rodrigues ha portato Equilibrio e Luce nella mia vita e molta consapevolezza.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Pratico Kundalini ed Hatha yoga dal 1985, Reiki di II\u00b0 livello e Floriterapia e durante gli studi in India mi specializzo in tecniche di respirazione,\u00a0 riabilitazione ed antistress diplomandomi come Ayurveda Terapista nei particolari e specifici massaggi usando pranayama e semplici asana per lo stretching completo del corpo. Nel 2020 ho frequentato L&#8217;Accademia di Selene Calloni Williams laureandomi in Yoga Sciamanico Integrale, approfondendo i tantissimi Yoga tra cui quello Giapponese.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Sono molto felice, grata ed onorata di essere tra le 32 insegnanti italiane abilitate e certificate da Dinah Rodrigues all\u2019insegnamento della preziosissima tecnica per la Salute della Donna. Dal 2019 tengo corsi, lezioni individuali e di gruppo nelle tre regioni italiane in cui vivo e che mi sono state assegnate da Dinah Rodrigues: l&#8217;Isola d\u2019Elba in Toscana, la Valle d\u2019Aosta ed il Veneto dove vado spesso a trovare la mia famiglia dando cos\u00ec l&#8217;opportunit\u00e0 di imparare il metodo terapeutico dello Yoga Ormonale di Dinah Rodrigues all&#8217;interno di meravigliose Ville palladiane e negli antichi Castelli pieni di storia ed Energia.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">All&#8217;Isola d&#8217;Elba insegno davanti al mare, in Valle d&#8217;Aosta nei boschi sotto il Monte Bianco.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Ringrazio l&#8217;Universo per la bellezza che mi dona ogni giorno.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Dal 2021 studio con impegno e determinazione\u00a0su libri, Dvd e posters la tecnica per l&#8217;Uomo e per il Diabete, acquistando sul sito di Dinah\u00a0https:\/\/www.dinahrodrigues.<wbr \/>com.br\/home-en e sono pronta a partire per il Brasile ed essere esaminata da lei per ricevere cosi il diploma per l&#8217;Uomo e lo stress e per il Diabete.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Diffondere e condividere la pratica \u201cdell\u2019ETERNA GIOVINEZZA\u201d in tutto il mondo \u00e8 il mio pi\u00f9 grande obiettivo.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Che tutto in te sia Luce!<\/div>\n<\/div>\n<div dir=\"auto\"><\/div>\n<p><a href=\"http:\/\/www.yogamissmary.com\">www.yogamissmary.com<\/a><\/p>\n<\/div>\n<\/div>\n","protected":false},"featured_media":3127,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"cybocfi_hide_featured_image":""},"local":[225],"class_list":["post-3126","professor","type-professor","status-publish","has-post-thumbnail","hentry","local-italy"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Miss Mary - NYTH<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/professor\/miss-mary\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Miss Mary - NYTH\" \/>\n<meta property=\"og:description\" content=\"Fin da bambina mi chiamano Miss\u00a0Mary. Quando Dinah nel 2019 mi ha consegnato il diploma ed il libro, ha scritto una dedica: \u201cRemember Yama &amp; Niyama\u201d\u00a0Praticare lo Yoga Ormonale con il metodo di Dinah Rodrigues ha portato Equilibrio e Luce nella mia vita e molta consapevolezza. Pratico Kundalini ed Hatha yoga dal 1985, Reiki di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/professor\/miss-mary\/\" \/>\n<meta property=\"og:site_name\" content=\"NYTH\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/wp-content\/uploads\/2025\/07\/March23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"247\" \/>\n\t<meta property=\"og:image:height\" content=\"323\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/en\\\/professor\\\/miss-mary\\\/\",\"url\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/en\\\/professor\\\/miss-mary\\\/\",\"name\":\"Miss Mary - NYTH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/en\\\/professor\\\/miss-mary\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/en\\\/professor\\\/miss-mary\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/en\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/March23.jpg\",\"datePublished\":\"2025-07-29T19:44:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/en\\\/professor\\\/miss-mary\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/en\\\/professor\\\/miss-mary\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/en\\\/professor\\\/miss-mary\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/en\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/March23.jpg\",\"contentUrl\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/en\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/March23.jpg\",\"width\":247,\"height\":323},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/en\\\/professor\\\/miss-mary\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Professores\",\"item\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/en\\\/professor\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Miss Mary\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/en\\\/\",\"name\":\"NYTH\",\"description\":\"N\u00facleo de Yoga Terapia Hormonal\",\"publisher\":{\"@id\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/en\\\/#organization\",\"name\":\"Nucleo Yoga Terapia Hormonal - NYTH\",\"url\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/en\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/en\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/favicon.png\",\"width\":500,\"height\":500,\"caption\":\"Nucleo Yoga Terapia Hormonal - NYTH\"},\"image\":{\"@id\":\"https:\\\/\\\/nucleoyogaterapiahormonal.com.br\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Miss Mary - NYTH","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/professor\/miss-mary\/","og_locale":"pt_BR","og_type":"article","og_title":"Miss Mary - NYTH","og_description":"Fin da bambina mi chiamano Miss\u00a0Mary. Quando Dinah nel 2019 mi ha consegnato il diploma ed il libro, ha scritto una dedica: \u201cRemember Yama &amp; Niyama\u201d\u00a0Praticare lo Yoga Ormonale con il metodo di Dinah Rodrigues ha portato Equilibrio e Luce nella mia vita e molta consapevolezza. Pratico Kundalini ed Hatha yoga dal 1985, Reiki di [&hellip;]","og_url":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/professor\/miss-mary\/","og_site_name":"NYTH","og_image":[{"width":247,"height":323,"url":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/wp-content\/uploads\/2025\/07\/March23.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/professor\/miss-mary\/","url":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/professor\/miss-mary\/","name":"Miss Mary - NYTH","isPartOf":{"@id":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/professor\/miss-mary\/#primaryimage"},"image":{"@id":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/professor\/miss-mary\/#primaryimage"},"thumbnailUrl":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/wp-content\/uploads\/2025\/07\/March23.jpg","datePublished":"2025-07-29T19:44:35+00:00","breadcrumb":{"@id":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/professor\/miss-mary\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nucleoyogaterapiahormonal.com.br\/en\/professor\/miss-mary\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/professor\/miss-mary\/#primaryimage","url":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/wp-content\/uploads\/2025\/07\/March23.jpg","contentUrl":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/wp-content\/uploads\/2025\/07\/March23.jpg","width":247,"height":323},{"@type":"BreadcrumbList","@id":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/professor\/miss-mary\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/"},{"@type":"ListItem","position":2,"name":"Professores","item":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/professor\/"},{"@type":"ListItem","position":3,"name":"Miss Mary"}]},{"@type":"WebSite","@id":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/#website","url":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/","name":"NYTH","description":"N\u00facleo de Yoga Terapia Hormonal","publisher":{"@id":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/#organization","name":"Nucleo Yoga Terapia Hormonal - NYTH","url":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/#\/schema\/logo\/image\/","url":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/wp-content\/uploads\/2022\/05\/favicon.png","contentUrl":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/wp-content\/uploads\/2022\/05\/favicon.png","width":500,"height":500,"caption":"Nucleo Yoga Terapia Hormonal - NYTH"},"image":{"@id":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/wp-json\/wp\/v2\/professor\/3126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/wp-json\/wp\/v2\/professor"}],"about":[{"href":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/wp-json\/wp\/v2\/types\/professor"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/wp-json\/wp\/v2\/media\/3127"}],"wp:attachment":[{"href":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/wp-json\/wp\/v2\/media?parent=3126"}],"wp:term":[{"taxonomy":"local","embeddable":true,"href":"https:\/\/nucleoyogaterapiahormonal.com.br\/en\/wp-json\/wp\/v2\/local?post=3126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}